{"id":2978,"date":"2026-04-07T03:27:49","date_gmt":"2026-04-07T03:27:49","guid":{"rendered":"https:\/\/berlinerbarocksolisten.de\/?p=2978"},"modified":"2026-04-07T03:57:04","modified_gmt":"2026-04-07T03:57:04","slug":"daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni","status":"publish","type":"post","link":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/","title":{"rendered":"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni"},"content":{"rendered":"\r\n<p><strong>Recording:<br \/><\/strong>B Sharp Studios<\/p>\r\n<p><strong>Executive Producer:<\/strong><br \/>Olaf Maninger, Marcus Forchner<\/p>\r\n<p><strong>Recording Producer:<br \/><\/strong>Philip Krause<\/p>\r\n<p><strong>Design<\/strong>:<br \/>Marek Polewski<\/p>\r\n<p><strong>Product Management:<\/strong><br \/>Zoe Howard, Felix Feustel<\/p>\r\n<p><strong>Photos:<\/strong><br \/>Stephan Rabold, Daishin Kashimoto<\/p>\r\n<p>\u2117 &amp; \u00a9 2026 Berlin Phil Media GmbH<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>Recording:B Sharp Studios Executive Producer:Olaf Maninger, Marcus Forchner Recording Producer:Philip Krause Design:Marek Polewski Product Management:Zoe Howard, Felix Feustel Photos:Stephan Rabold, Daishin Kashimoto \u2117 &amp; \u00a9 2026 Berlin Phil Media GmbH<\/p>\n","protected":false},"author":8,"featured_media":2981,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[58],"tags":[],"class_list":["post-2978","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cds-en"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni - Berliner Barock Solisten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni - Berliner Barock Solisten\" \/>\n<meta property=\"og:description\" content=\"Recording:B Sharp Studios Executive Producer:Olaf Maninger, Marcus Forchner Recording Producer:Philip Krause Design:Marek Polewski Product Management:Zoe Howard, Felix Feustel Photos:Stephan Rabold, Daishin Kashimoto \u2117 &amp; \u00a9 2026 Berlin Phil Media GmbH\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Berliner Barock Solisten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/berlinerbarocksolisten\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-07T03:27:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-07T03:57:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/berlinerbarocksolisten.de\/wp-content\/uploads\/2026\/04\/BPHR-260541-Vivaldi-CD-Cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"938\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"wamrhein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"wamrhein\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/\"},\"author\":{\"name\":\"wamrhein\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#\\\/schema\\\/person\\\/9ea1ff6bfdedfd991071c523663d1b29\"},\"headline\":\"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni\",\"datePublished\":\"2026-04-07T03:27:49+00:00\",\"dateModified\":\"2026-04-07T03:57:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/\"},\"wordCount\":40,\"image\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPHR-260541-Vivaldi-CD-Cover.jpg\",\"articleSection\":[\"CDs\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/\",\"url\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/\",\"name\":\"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni - Berliner Barock Solisten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPHR-260541-Vivaldi-CD-Cover.jpg\",\"datePublished\":\"2026-04-07T03:27:49+00:00\",\"dateModified\":\"2026-04-07T03:57:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#\\\/schema\\\/person\\\/9ea1ff6bfdedfd991071c523663d1b29\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPHR-260541-Vivaldi-CD-Cover.jpg\",\"contentUrl\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/BPHR-260541-Vivaldi-CD-Cover.jpg\",\"width\":1000,\"height\":938},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/cds-en\\\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#website\",\"url\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\",\"name\":\"Berliner Barock Solisten\",\"description\":\"Berliner Barock Solisten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#\\\/schema\\\/person\\\/9ea1ff6bfdedfd991071c523663d1b29\",\"name\":\"wamrhein\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8b1642192adde9a882848bc2ac64b4fbf5d7a3ae74df64657a789762e8d9a1d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8b1642192adde9a882848bc2ac64b4fbf5d7a3ae74df64657a789762e8d9a1d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8b1642192adde9a882848bc2ac64b4fbf5d7a3ae74df64657a789762e8d9a1d?s=96&d=mm&r=g\",\"caption\":\"wamrhein\"},\"url\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/en\\\/author\\\/wamrhein\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni - Berliner Barock Solisten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/","og_locale":"en_US","og_type":"article","og_title":"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni - Berliner Barock Solisten","og_description":"Recording:B Sharp Studios Executive Producer:Olaf Maninger, Marcus Forchner Recording Producer:Philip Krause Design:Marek Polewski Product Management:Zoe Howard, Felix Feustel Photos:Stephan Rabold, Daishin Kashimoto \u2117 &amp; \u00a9 2026 Berlin Phil Media GmbH","og_url":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/","og_site_name":"Berliner Barock Solisten","article_publisher":"https:\/\/www.facebook.com\/berlinerbarocksolisten","article_published_time":"2026-04-07T03:27:49+00:00","article_modified_time":"2026-04-07T03:57:04+00:00","og_image":[{"width":1000,"height":938,"url":"https:\/\/berlinerbarocksolisten.de\/wp-content\/uploads\/2026\/04\/BPHR-260541-Vivaldi-CD-Cover.jpg","type":"image\/jpeg"}],"author":"wamrhein","twitter_card":"summary_large_image","twitter_misc":{"Written by":"wamrhein","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#article","isPartOf":{"@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/"},"author":{"name":"wamrhein","@id":"https:\/\/berlinerbarocksolisten.de\/#\/schema\/person\/9ea1ff6bfdedfd991071c523663d1b29"},"headline":"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni","datePublished":"2026-04-07T03:27:49+00:00","dateModified":"2026-04-07T03:57:04+00:00","mainEntityOfPage":{"@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/"},"wordCount":40,"image":{"@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#primaryimage"},"thumbnailUrl":"https:\/\/berlinerbarocksolisten.de\/wp-content\/uploads\/2026\/04\/BPHR-260541-Vivaldi-CD-Cover.jpg","articleSection":["CDs"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/","url":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/","name":"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni - Berliner Barock Solisten","isPartOf":{"@id":"https:\/\/berlinerbarocksolisten.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#primaryimage"},"image":{"@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#primaryimage"},"thumbnailUrl":"https:\/\/berlinerbarocksolisten.de\/wp-content\/uploads\/2026\/04\/BPHR-260541-Vivaldi-CD-Cover.jpg","datePublished":"2026-04-07T03:27:49+00:00","dateModified":"2026-04-07T03:57:04+00:00","author":{"@id":"https:\/\/berlinerbarocksolisten.de\/#\/schema\/person\/9ea1ff6bfdedfd991071c523663d1b29"},"breadcrumb":{"@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#primaryimage","url":"https:\/\/berlinerbarocksolisten.de\/wp-content\/uploads\/2026\/04\/BPHR-260541-Vivaldi-CD-Cover.jpg","contentUrl":"https:\/\/berlinerbarocksolisten.de\/wp-content\/uploads\/2026\/04\/BPHR-260541-Vivaldi-CD-Cover.jpg","width":1000,"height":938},{"@type":"BreadcrumbList","@id":"https:\/\/berlinerbarocksolisten.de\/en\/cds-en\/daishin-kashimoto-antonio-vivaldi-le-quattro-stagioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/berlinerbarocksolisten.de\/"},{"@type":"ListItem","position":2,"name":"Daishin Kashimoto \u2013 Antonio Vivaldi: Le quattro stagioni"}]},{"@type":"WebSite","@id":"https:\/\/berlinerbarocksolisten.de\/#website","url":"https:\/\/berlinerbarocksolisten.de\/","name":"Berliner Barock Solisten","description":"Berliner Barock Solisten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berlinerbarocksolisten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/berlinerbarocksolisten.de\/#\/schema\/person\/9ea1ff6bfdedfd991071c523663d1b29","name":"wamrhein","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/d8b1642192adde9a882848bc2ac64b4fbf5d7a3ae74df64657a789762e8d9a1d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8b1642192adde9a882848bc2ac64b4fbf5d7a3ae74df64657a789762e8d9a1d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8b1642192adde9a882848bc2ac64b4fbf5d7a3ae74df64657a789762e8d9a1d?s=96&d=mm&r=g","caption":"wamrhein"},"url":"https:\/\/berlinerbarocksolisten.de\/en\/author\/wamrhein\/"}]}},"_links":{"self":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/posts\/2978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/comments?post=2978"}],"version-history":[{"count":2,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/posts\/2978\/revisions"}],"predecessor-version":[{"id":2989,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/posts\/2978\/revisions\/2989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/media\/2981"}],"wp:attachment":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/media?parent=2978"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/categories?post=2978"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/tags?post=2978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}