{"id":1247,"date":"2022-02-25T19:29:06","date_gmt":"2022-02-25T19:29:06","guid":{"rendered":"http:\/\/neu.berlinerbarocksolisten.de\/clone-of-generated-homepage\/"},"modified":"2025-06-05T09:10:52","modified_gmt":"2025-06-05T09:10:52","slug":"clone-of-generated-homepage","status":"publish","type":"page","link":"https:\/\/berlinerbarocksolisten.de\/en\/","title":{"rendered":"Home page"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/10\/g10-3.png\" alt=\"\"><\/p>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"header_transparent_noplaceholder\":false,\"height\":\"viewport\",\"height_offset_top\":true,\"image_position\":\"center-center\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"middle\",\"video\":\"wp-content\\\/uploads\\\/2022\\\/01\\\/website-footage4-slim.m4v\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/10\\\/g10-2.png\",\"image_svg_color\":\"emphasis\",\"image_width\":\"350\",\"margin\":\"default\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"video\",\"props\":{\"css\":\".el-element{\\nborder: 2px solid #FFF;\\n}\",\"margin\":\"default\",\"margin_remove_top\":true,\"video\":\"https:\\\/\\\/youtu.be\\\/Qt-3b2zM6Og\",\"video_controls\":true,\"video_width\":\"1000\"}}]}],\"props\":{\"layout\":\"1-2,1-2\",\"status\":\"disabled\"}},{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"image\",\"props\":{\"image\":\"wp-content\\\/uploads\\\/2021\\\/10\\\/g10-3.png\",\"image_svg_color\":\"emphasis\",\"image_width\":\"350\",\"margin\":\"default\",\"text_align\":\"center\"}}]}]}]}],\"version\":\"4.5.19\",\"yooessentialsVersion\":\"2.3.12\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1247","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Home page - Berliner Barock Solisten<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/berlinerbarocksolisten.de\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Home page - Berliner Barock Solisten\" \/>\n<meta property=\"og:url\" content=\"https:\/\/berlinerbarocksolisten.de\/\" \/>\n<meta property=\"og:site_name\" content=\"Berliner Barock Solisten\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/berlinerbarocksolisten\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-05T09:10:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\",\"url\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\",\"name\":\"Home page - Berliner Barock Solisten\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#website\"},\"datePublished\":\"2022-02-25T19:29:06+00:00\",\"dateModified\":\"2025-06-05T09:10:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home page\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/#website\",\"url\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/\",\"name\":\"Berliner Barock Solisten\",\"description\":\"Berliner Barock Solisten\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/berlinerbarocksolisten.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Home page - Berliner Barock Solisten","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/berlinerbarocksolisten.de\/","og_locale":"en_US","og_type":"article","og_title":"Home page - Berliner Barock Solisten","og_url":"https:\/\/berlinerbarocksolisten.de\/","og_site_name":"Berliner Barock Solisten","article_publisher":"https:\/\/www.facebook.com\/berlinerbarocksolisten","article_modified_time":"2025-06-05T09:10:52+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/berlinerbarocksolisten.de\/","url":"https:\/\/berlinerbarocksolisten.de\/","name":"Home page - Berliner Barock Solisten","isPartOf":{"@id":"https:\/\/berlinerbarocksolisten.de\/#website"},"datePublished":"2022-02-25T19:29:06+00:00","dateModified":"2025-06-05T09:10:52+00:00","breadcrumb":{"@id":"https:\/\/berlinerbarocksolisten.de\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/berlinerbarocksolisten.de\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/berlinerbarocksolisten.de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/berlinerbarocksolisten.de\/"},{"@type":"ListItem","position":2,"name":"Home page"}]},{"@type":"WebSite","@id":"https:\/\/berlinerbarocksolisten.de\/#website","url":"https:\/\/berlinerbarocksolisten.de\/","name":"Berliner Barock Solisten","description":"Berliner Barock Solisten","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/berlinerbarocksolisten.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/pages\/1247","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/comments?post=1247"}],"version-history":[{"count":12,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/pages\/1247\/revisions"}],"predecessor-version":[{"id":2840,"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/pages\/1247\/revisions\/2840"}],"wp:attachment":[{"href":"https:\/\/berlinerbarocksolisten.de\/en\/wp-json\/wp\/v2\/media?parent=1247"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}